{"id":41076,"date":"2020-09-03T09:55:47","date_gmt":"2020-09-03T07:55:47","guid":{"rendered":"https:\/\/www.garvanacoustic.com\/?p=41076"},"modified":"2020-10-14T09:18:38","modified_gmt":"2020-10-14T07:18:38","slug":"talk-to-robert-eno-how-audio-systems-in-clubs-have-changed","status":"publish","type":"post","link":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/","title":{"rendered":"A talk with Robert-Eno. How audio systems in clubs have changed"},"content":{"rendered":"<section class=\"no-padding sm-no-padding\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column hcode-column-container  col-xs-mobile-fullwidth\" data-front-class=\"col-xs-mobile-fullwidth front-column-class\"><div class=\"vc-column-innner-wrapper\"><p>A nice talk with Robert-Eno about how audio systems in clubs have changed over time.<\/p>\n<p>Robert-Eno is one of the most important dance-music Italian artists. Together with Mark Lanzetta he founded Relight Orchestra, a recording project that composed the hit \"Elegibo\" and the remix of \"Splendido Splendente\" by Donatella Rettore for the 40th anniversary of the song.<\/p>\n<p>Robert-Eno<br \/>\n<a href=\"https:\/\/www.relightorchestra.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.relightorchestra.it\/<\/a><\/p>\n<div class=\"fit-videos\"><iframe loading=\"lazy\" width=\"1200\" height=\"675\" webkitAllowFullScreen mozallowfullscreen allowFullScreen src=\"https:\/\/www.youtube.com\/embed\/VO3O4XA6HA4?rel=0&amp;controls=0&amp;showinfo=0&autoplay=0&loop=0\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>A nice talk with Robert-Eno about how audio systems in clubs have changed over time. Robert-Eno is one of the most important dance-music Italian artists. Together with Mark Lanzetta he founded Relight Orchestra, a recording project that composed the hit &#8220;Elegibo&#8221; and the remix of &#8220;Splendido Splendente&#8221; by Donatella Rettore for the 40th anniversary of [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":38142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_joinchat":[],"footnotes":""},"categories":[117],"tags":[],"class_list":["post-41076","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-news-lifestyle","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A talk with Robert-Eno. How audio systems in clubs have changed - Garvan Acoustic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A talk with Robert-Eno. How audio systems in clubs have changed\" \/>\n<meta property=\"og:description\" content=\"A nice talk with Robert-Eno about how audio systems in clubs have changed over time. Robert-Eno is one of the most important dance-music Italian artists. Together with Mark Lanzetta he founded Relight Orchestra, a recording project that composed the hit &quot;Elegibo&quot; and the remix of &quot;Splendido Splendente&quot; by Donatella Rettore for the 40th anniversary of [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/\" \/>\n<meta property=\"og:site_name\" content=\"Garvan Acoustic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/garvanacoustic\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-03T07:55:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T07:18:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tommaso Minardi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tommaso Minardi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/\"},\"author\":{\"name\":\"Tommaso Minardi\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#\\\/schema\\\/person\\\/6a1c1645f07f7a0aa5e018c2f909f355\"},\"headline\":\"A talk with Robert-Eno. How audio systems in clubs have changed\",\"datePublished\":\"2020-09-03T07:55:47+00:00\",\"dateModified\":\"2020-10-14T07:18:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/\"},\"wordCount\":123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg\",\"articleSection\":[\"News &amp; Lifestyle\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/\",\"name\":\"A talk with Robert-Eno. How audio systems in clubs have changed - Garvan Acoustic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg\",\"datePublished\":\"2020-09-03T07:55:47+00:00\",\"dateModified\":\"2020-10-14T07:18:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Talk to Robert-Eno: audio systems in clubs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A talk with Robert-Eno. How audio systems in clubs have changed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/\",\"name\":\"Garvan Acoustic\",\"description\":\"Casse acustiche e amplificatori audio: scopri la qualit\u00e0 del Made in Italy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#organization\",\"name\":\"Garvan Acoustic\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/garvan-acoustic-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/garvan-acoustic-logo.png\",\"width\":400,\"height\":161,\"caption\":\"Garvan Acoustic\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/garvanacoustic\",\"https:\\\/\\\/www.instagram.com\\\/garvanacoustic\\\/\"],\"description\":\"Produttori di Diffusori Acustici e Pannelli Fonoassorbenti Made in Italy\",\"email\":\"garvan@garvanacoustic.com\",\"telephone\":\"0546 682097\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#\\\/schema\\\/person\\\/6a1c1645f07f7a0aa5e018c2f909f355\",\"name\":\"Tommaso Minardi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"caption\":\"Tommaso Minardi\"},\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/author\\\/studioin3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A talk with Robert-Eno. How audio systems in clubs have changed - Garvan Acoustic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/","og_locale":"en_US","og_type":"article","og_title":"A talk with Robert-Eno. How audio systems in clubs have changed","og_description":"A nice talk with Robert-Eno about how audio systems in clubs have changed over time. Robert-Eno is one of the most important dance-music Italian artists. Together with Mark Lanzetta he founded Relight Orchestra, a recording project that composed the hit \"Elegibo\" and the remix of \"Splendido Splendente\" by Donatella Rettore for the 40th anniversary of [&hellip;]","og_url":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/","og_site_name":"Garvan Acoustic","article_publisher":"https:\/\/www.facebook.com\/garvanacoustic","article_published_time":"2020-09-03T07:55:47+00:00","article_modified_time":"2020-10-14T07:18:38+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg","type":"image\/jpeg"}],"author":"Tommaso Minardi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tommaso Minardi","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/#article","isPartOf":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/"},"author":{"name":"Tommaso Minardi","@id":"https:\/\/www.garvanacoustic.com\/en\/#\/schema\/person\/6a1c1645f07f7a0aa5e018c2f909f355"},"headline":"A talk with Robert-Eno. How audio systems in clubs have changed","datePublished":"2020-09-03T07:55:47+00:00","dateModified":"2020-10-14T07:18:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/"},"wordCount":123,"commentCount":0,"publisher":{"@id":"https:\/\/www.garvanacoustic.com\/en\/#organization"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg","articleSection":["News &amp; Lifestyle"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/","url":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/","name":"A talk with Robert-Eno. How audio systems in clubs have changed - Garvan Acoustic","isPartOf":{"@id":"https:\/\/www.garvanacoustic.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/#primaryimage"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg","datePublished":"2020-09-03T07:55:47+00:00","dateModified":"2020-10-14T07:18:38+00:00","breadcrumb":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/#primaryimage","url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg","contentUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/f253b9a571d2fd992a831ba40c7a7089_118595383_1603934896479718_7813741995789854115_n.jpg","width":1280,"height":720,"caption":"Talk to Robert-Eno: audio systems in clubs"},{"@type":"BreadcrumbList","@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/talk-to-robert-eno-how-audio-systems-in-clubs-have-changed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.garvanacoustic.com\/en\/"},{"@type":"ListItem","position":2,"name":"A talk with Robert-Eno. How audio systems in clubs have changed"}]},{"@type":"WebSite","@id":"https:\/\/www.garvanacoustic.com\/en\/#website","url":"https:\/\/www.garvanacoustic.com\/en\/","name":"Garvan Acoustic","description":"Casse acustiche e amplificatori audio: scopri la qualit\u00e0 del Made in Italy","publisher":{"@id":"https:\/\/www.garvanacoustic.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.garvanacoustic.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.garvanacoustic.com\/en\/#organization","name":"Garvan Acoustic","url":"https:\/\/www.garvanacoustic.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.garvanacoustic.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2018\/07\/garvan-acoustic-logo.png","contentUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2018\/07\/garvan-acoustic-logo.png","width":400,"height":161,"caption":"Garvan Acoustic"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/garvanacoustic","https:\/\/www.instagram.com\/garvanacoustic\/"],"description":"Produttori di Diffusori Acustici e Pannelli Fonoassorbenti Made in Italy","email":"garvan@garvanacoustic.com","telephone":"0546 682097"},{"@type":"Person","@id":"https:\/\/www.garvanacoustic.com\/en\/#\/schema\/person\/6a1c1645f07f7a0aa5e018c2f909f355","name":"Tommaso Minardi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","caption":"Tommaso Minardi"},"url":"https:\/\/www.garvanacoustic.com\/en\/author\/studioin3\/"}]}},"_links":{"self":[{"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/posts\/41076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/comments?post=41076"}],"version-history":[{"count":4,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/posts\/41076\/revisions"}],"predecessor-version":[{"id":41162,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/posts\/41076\/revisions\/41162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/media\/38142"}],"wp:attachment":[{"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/media?parent=41076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/categories?post=41076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/tags?post=41076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}