{"id":58372,"date":"2022-08-12T12:38:31","date_gmt":"2022-08-12T10:38:31","guid":{"rendered":"https:\/\/www.garvanacoustic.com\/?p=58372"},"modified":"2022-12-20T12:42:44","modified_gmt":"2022-12-20T11:42:44","slug":"goccia-ready-for-a-special-new-graphic-print","status":"publish","type":"post","link":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/","title":{"rendered":"Goccia: ready for a special new graphic print"},"content":{"rendered":"<section class=\"no-padding\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column hcode-column-container  col-xs-mobile-fullwidth\" data-front-class=\"col-xs-mobile-fullwidth front-column-class\"><div class=\"vc-column-innner-wrapper\"><div class=\"fit-videos\"><iframe loading=\"lazy\" width=\"866\" height=\"487\"  src=\"https:\/\/youtube.com\/embed\/W71YBBkZ2ik?autoplay=0&loop=0\"><\/iframe><\/div><p>&nbsp;<\/p>\n<p>We delivered the Goccia speakers by Garvan to Davide Degli Innocenti (DID) to create a special graphic print that we will reveal soon. Project by Aldo Drudi - <a href=\"https:\/\/www.facebook.com\/airgaragerimini\/?__cft__%5b0%5d=AZWcJIO9Xi4C4mEPXLBN4JSBdITcnz7L37O1spC0xu8DBPbuULBunOhM6LGji9_hhIajqQb5xqGMOUTVAHbxuAI7xwg_ru9zqI_C3Q3r8XImS2Plv5gtdKIyyNPW6nKFkHzwVkpOaBl5FxbizCB1zJ1E&amp;__tn__=kK-R\">Drudi Performance<\/a><\/p>\n<p><a href=\"\/?p=27383\">Learn more on Goccia by Garvan Acoustic\u00a0<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>&nbsp; We delivered the Goccia speakers by Garvan to Davide Degli Innocenti (DID) to create a special graphic print that we will reveal soon. Project by Aldo Drudi &#8211; Drudi Performance Learn more on Goccia by Garvan Acoustic\u00a0<\/p>\n","protected":false},"author":8,"featured_media":58297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_joinchat":[],"footnotes":""},"categories":[117],"tags":[],"class_list":["post-58372","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-news-lifestyle","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Goccia: ready for a special new graphic print - Garvan Acoustic<\/title>\n<meta name=\"description\" content=\"We delivered the Goccia speakers by Garvan to Davide Degli Innocenti (DID) to create a special graphic print that we will reveal soon. Project by Aldo Drudi - Drudi Performance\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Goccia: ready for a special new graphic print\" \/>\n<meta property=\"og:description\" content=\"We delivered the Goccia speakers by Garvan to Davide Degli Innocenti (DID) to create a special graphic print that we will reveal soon. Project by Aldo Drudi - Drudi Performance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/\" \/>\n<meta property=\"og:site_name\" content=\"Garvan Acoustic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/garvanacoustic\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-12T10:38:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-20T11:42:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2022\/12\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tommaso Minardi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tommaso Minardi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/\"},\"author\":{\"name\":\"Tommaso Minardi\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#\\\/schema\\\/person\\\/6a1c1645f07f7a0aa5e018c2f909f355\"},\"headline\":\"Goccia: ready for a special new graphic print\",\"datePublished\":\"2022-08-12T10:38:31+00:00\",\"dateModified\":\"2022-12-20T11:42:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/\"},\"wordCount\":84,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg\",\"articleSection\":[\"News &amp; Lifestyle\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/\",\"name\":\"Goccia: ready for a special new graphic print - Garvan Acoustic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg\",\"datePublished\":\"2022-08-12T10:38:31+00:00\",\"dateModified\":\"2022-12-20T11:42:44+00:00\",\"description\":\"We delivered the Goccia speakers by Garvan to Davide Degli Innocenti (DID) to create a special graphic print that we will reveal soon. Project by Aldo Drudi - Drudi Performance\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg\",\"contentUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Goccia speakers, ready to be decorated with new graphics\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/news-lifestyle\\\/goccia-ready-for-a-special-new-graphic-print\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Goccia: ready for a special new graphic print\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/\",\"name\":\"Garvan Acoustic\",\"description\":\"Casse acustiche e amplificatori audio: scopri la qualit\u00e0 del Made in Italy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#organization\",\"name\":\"Garvan Acoustic\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/garvan-acoustic-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/garvan-acoustic-logo.png\",\"width\":400,\"height\":161,\"caption\":\"Garvan Acoustic\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/garvanacoustic\",\"https:\\\/\\\/www.instagram.com\\\/garvanacoustic\\\/\"],\"description\":\"Produttori di Diffusori Acustici e Pannelli Fonoassorbenti Made in Italy\",\"email\":\"garvan@garvanacoustic.com\",\"telephone\":\"0546 682097\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/#\\\/schema\\\/person\\\/6a1c1645f07f7a0aa5e018c2f909f355\",\"name\":\"Tommaso Minardi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"caption\":\"Tommaso Minardi\"},\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/en\\\/author\\\/studioin3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Goccia: ready for a special new graphic print - Garvan Acoustic","description":"We delivered the Goccia speakers by Garvan to Davide Degli Innocenti (DID) to create a special graphic print that we will reveal soon. Project by Aldo Drudi - Drudi Performance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/","og_locale":"en_US","og_type":"article","og_title":"Goccia: ready for a special new graphic print","og_description":"We delivered the Goccia speakers by Garvan to Davide Degli Innocenti (DID) to create a special graphic print that we will reveal soon. Project by Aldo Drudi - Drudi Performance","og_url":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/","og_site_name":"Garvan Acoustic","article_publisher":"https:\/\/www.facebook.com\/garvanacoustic","article_published_time":"2022-08-12T10:38:31+00:00","article_modified_time":"2022-12-20T11:42:44+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2022\/12\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg","type":"image\/jpeg"}],"author":"Tommaso Minardi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tommaso Minardi","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/#article","isPartOf":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/"},"author":{"name":"Tommaso Minardi","@id":"https:\/\/www.garvanacoustic.com\/en\/#\/schema\/person\/6a1c1645f07f7a0aa5e018c2f909f355"},"headline":"Goccia: ready for a special new graphic print","datePublished":"2022-08-12T10:38:31+00:00","dateModified":"2022-12-20T11:42:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/"},"wordCount":84,"commentCount":0,"publisher":{"@id":"https:\/\/www.garvanacoustic.com\/en\/#organization"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/#primaryimage"},"thumbnailUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2022\/12\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg","articleSection":["News &amp; Lifestyle"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/","url":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/","name":"Goccia: ready for a special new graphic print - Garvan Acoustic","isPartOf":{"@id":"https:\/\/www.garvanacoustic.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/#primaryimage"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/#primaryimage"},"thumbnailUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2022\/12\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg","datePublished":"2022-08-12T10:38:31+00:00","dateModified":"2022-12-20T11:42:44+00:00","description":"We delivered the Goccia speakers by Garvan to Davide Degli Innocenti (DID) to create a special graphic print that we will reveal soon. Project by Aldo Drudi - Drudi Performance","breadcrumb":{"@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/#primaryimage","url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2022\/12\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg","contentUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2022\/12\/goccia-speakers-ready-to-be-decorated-with-new-graphics.jpg","width":1280,"height":720,"caption":"Goccia speakers, ready to be decorated with new graphics"},{"@type":"BreadcrumbList","@id":"https:\/\/www.garvanacoustic.com\/en\/news-lifestyle\/goccia-ready-for-a-special-new-graphic-print\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.garvanacoustic.com\/en\/"},{"@type":"ListItem","position":2,"name":"Goccia: ready for a special new graphic print"}]},{"@type":"WebSite","@id":"https:\/\/www.garvanacoustic.com\/en\/#website","url":"https:\/\/www.garvanacoustic.com\/en\/","name":"Garvan Acoustic","description":"Casse acustiche e amplificatori audio: scopri la qualit\u00e0 del Made in Italy","publisher":{"@id":"https:\/\/www.garvanacoustic.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.garvanacoustic.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.garvanacoustic.com\/en\/#organization","name":"Garvan Acoustic","url":"https:\/\/www.garvanacoustic.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.garvanacoustic.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2018\/07\/garvan-acoustic-logo.png","contentUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2018\/07\/garvan-acoustic-logo.png","width":400,"height":161,"caption":"Garvan Acoustic"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/garvanacoustic","https:\/\/www.instagram.com\/garvanacoustic\/"],"description":"Produttori di Diffusori Acustici e Pannelli Fonoassorbenti Made in Italy","email":"garvan@garvanacoustic.com","telephone":"0546 682097"},{"@type":"Person","@id":"https:\/\/www.garvanacoustic.com\/en\/#\/schema\/person\/6a1c1645f07f7a0aa5e018c2f909f355","name":"Tommaso Minardi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","caption":"Tommaso Minardi"},"url":"https:\/\/www.garvanacoustic.com\/en\/author\/studioin3\/"}]}},"_links":{"self":[{"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/posts\/58372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/comments?post=58372"}],"version-history":[{"count":5,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/posts\/58372\/revisions"}],"predecessor-version":[{"id":58377,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/posts\/58372\/revisions\/58377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/media\/58297"}],"wp:attachment":[{"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/media?parent=58372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/categories?post=58372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/en\/wp-json\/wp\/v2\/tags?post=58372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}