{"id":46332,"date":"2020-03-20T14:10:15","date_gmt":"2020-03-20T13:10:15","guid":{"rendered":"https:\/\/www.garvanacoustic.com\/?p=46332"},"modified":"2021-03-09T14:17:27","modified_gmt":"2021-03-09T13:17:27","slug":"audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t","status":"publish","type":"post","link":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/","title":{"rendered":"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi &#8211; C.A.T."},"content":{"rendered":"<section class=\"no-padding\" style=\"background-color:#000000;\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column hcode-column-container vc_col-sm-12 col-xs-mobile-fullwidth wow fadeIn\" data-front-class=\"col-xs-mobile-fullwidth\"><div class=\"vc-column-innner-wrapper\"><div class=\"fit-videos\"><iframe loading=\"lazy\" width=\"1200\" height=\"675\" webkitAllowFullScreen mozallowfullscreen allowFullScreen src=\"https:\/\/www.youtube.com\/embed\/P7Bh2x8YJoY?rel=0&amp;controls=0&amp;showinfo=0&autoplay=0&loop=0\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/section><section><div class=\"container\"><div class=\"row\"><div class=\"wpb_column hcode-column-container  col-xs-mobile-fullwidth\" data-front-class=\"col-xs-mobile-fullwidth front-column-class\"><div class=\"vc-column-innner-wrapper\"><p>Dans cette vid\u00e9o, enregistr\u00e9e avant l'urgence COVID-19, Davide Bertozzi de C.A.T. nous raconte une histoire de d'un syst\u00e8me audio multiroom fabriqu\u00e9 avec des enceintes acoustiques encastrables Garvan.<\/p>\n<p>Les zones sont g\u00e9r\u00e9es de mani\u00e8re ind\u00e9pendante et via une application de contr\u00f4le. Les haut-parleurs sont int\u00e9gr\u00e9s dans la maison et sont utilis\u00e9s pour \u00e9couter de la musique et des films.<\/p>\n<p>Installation par C.A.T. Davide Bertozzi, revendeur agr\u00e9\u00e9 Garvan Acoustic<\/p>\n<p><a href=\"https:\/\/youtu.be\/Lq9Ym0Dp3HM\">Regardez la vid\u00e9o pr\u00e9c\u00e9dente avec Davide Bertozzi<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Dans cette vid\u00e9o, enregistr\u00e9e avant l&rsquo;urgence COVID-19, Davide Bertozzi de C.A.T. nous raconte une histoire de d&rsquo;un syst\u00e8me audio multiroom fabriqu\u00e9 avec des enceintes acoustiques encastrables Garvan. Les zones sont g\u00e9r\u00e9es de mani\u00e8re ind\u00e9pendante et via une application de contr\u00f4le. Les haut-parleurs sont int\u00e9gr\u00e9s dans la maison et sont utilis\u00e9s pour \u00e9couter de la musique [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":38973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_joinchat":[],"footnotes":""},"categories":[132],"tags":[],"class_list":["post-46332","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-news-lifestyle","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi - C.A.T. - Garvan Acoustic<\/title>\n<meta name=\"description\" content=\"Dans cette vid\u00e9o, enregistr\u00e9e avant l&#039;urgence COVID-19, Davide Bertozzi de C.A.T. nous raconte une histoire de d&#039;un syst\u00e8me audio multiroom fabriqu\u00e9 avec des enceintes acoustiques encastrables Garvan.Les zones sont g\u00e9r\u00e9es de mani\u00e8re ind\u00e9pendante et via une application de contr\u00f4le. Les haut-parleurs sont int\u00e9gr\u00e9s dans la maison et sont utilis\u00e9s pour \u00e9couter de la musique et des films.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi - C.A.T.\" \/>\n<meta property=\"og:description\" content=\"Dans cette vid\u00e9o, enregistr\u00e9e avant l&#039;urgence COVID-19, Davide Bertozzi de C.A.T. nous raconte une histoire de d&#039;un syst\u00e8me audio multiroom fabriqu\u00e9 avec des enceintes acoustiques encastrables Garvan.Les zones sont g\u00e9r\u00e9es de mani\u00e8re ind\u00e9pendante et via une application de contr\u00f4le. Les haut-parleurs sont int\u00e9gr\u00e9s dans la maison et sont utilis\u00e9s pour \u00e9couter de la musique et des films.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/\" \/>\n<meta property=\"og:site_name\" content=\"Garvan Acoustic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/garvanacoustic\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T13:10:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-09T13:17:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/maxresdefault-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tommaso Minardi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tommaso Minardi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/\"},\"author\":{\"name\":\"Tommaso Minardi\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#\\\/schema\\\/person\\\/6a1c1645f07f7a0aa5e018c2f909f355\"},\"headline\":\"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi &#8211; C.A.T.\",\"datePublished\":\"2020-03-20T13:10:15+00:00\",\"dateModified\":\"2021-03-09T13:17:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/\"},\"wordCount\":179,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/maxresdefault-5.jpg\",\"articleSection\":[\"News &amp; Lifestyle\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/\",\"name\":\"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi - C.A.T. - Garvan Acoustic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/maxresdefault-5.jpg\",\"datePublished\":\"2020-03-20T13:10:15+00:00\",\"dateModified\":\"2021-03-09T13:17:27+00:00\",\"description\":\"Dans cette vid\u00e9o, enregistr\u00e9e avant l'urgence COVID-19, Davide Bertozzi de C.A.T. nous raconte une histoire de d'un syst\u00e8me audio multiroom fabriqu\u00e9 avec des enceintes acoustiques encastrables Garvan.Les zones sont g\u00e9r\u00e9es de mani\u00e8re ind\u00e9pendante et via une application de contr\u00f4le. Les haut-parleurs sont int\u00e9gr\u00e9s dans la maison et sont utilis\u00e9s pour \u00e9couter de la musique et des films.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/maxresdefault-5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/maxresdefault-5.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Audio Multiroom con diffusori da incasso,\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/news-lifestyle\\\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi &#8211; C.A.T.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/\",\"name\":\"Garvan Acoustic\",\"description\":\"Diffusori e trattamento acustico: scopri la qualit\u00e0 del Made in Italy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#organization\",\"name\":\"Garvan Acoustic\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/garvan-acoustic-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.garvanacoustic.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/garvan-acoustic-logo.png\",\"width\":400,\"height\":161,\"caption\":\"Garvan Acoustic\"},\"image\":{\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/garvanacoustic\",\"https:\\\/\\\/www.instagram.com\\\/garvanacoustic\\\/\"],\"description\":\"Produttori di Diffusori Acustici e Pannelli Fonoassorbenti Made in Italy\",\"email\":\"garvan@garvanacoustic.com\",\"telephone\":\"0546 682097\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/#\\\/schema\\\/person\\\/6a1c1645f07f7a0aa5e018c2f909f355\",\"name\":\"Tommaso Minardi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g\",\"caption\":\"Tommaso Minardi\"},\"url\":\"https:\\\/\\\/www.garvanacoustic.com\\\/fr\\\/author\\\/studioin3\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi - C.A.T. - Garvan Acoustic","description":"Dans cette vid\u00e9o, enregistr\u00e9e avant l'urgence COVID-19, Davide Bertozzi de C.A.T. nous raconte une histoire de d'un syst\u00e8me audio multiroom fabriqu\u00e9 avec des enceintes acoustiques encastrables Garvan.Les zones sont g\u00e9r\u00e9es de mani\u00e8re ind\u00e9pendante et via une application de contr\u00f4le. Les haut-parleurs sont int\u00e9gr\u00e9s dans la maison et sont utilis\u00e9s pour \u00e9couter de la musique et des films.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/","og_locale":"fr_FR","og_type":"article","og_title":"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi - C.A.T.","og_description":"Dans cette vid\u00e9o, enregistr\u00e9e avant l'urgence COVID-19, Davide Bertozzi de C.A.T. nous raconte une histoire de d'un syst\u00e8me audio multiroom fabriqu\u00e9 avec des enceintes acoustiques encastrables Garvan.Les zones sont g\u00e9r\u00e9es de mani\u00e8re ind\u00e9pendante et via une application de contr\u00f4le. Les haut-parleurs sont int\u00e9gr\u00e9s dans la maison et sont utilis\u00e9s pour \u00e9couter de la musique et des films.","og_url":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/","og_site_name":"Garvan Acoustic","article_publisher":"https:\/\/www.facebook.com\/garvanacoustic","article_published_time":"2020-03-20T13:10:15+00:00","article_modified_time":"2021-03-09T13:17:27+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/maxresdefault-5.jpg","type":"image\/jpeg"}],"author":"Tommaso Minardi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Tommaso Minardi","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/#article","isPartOf":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/"},"author":{"name":"Tommaso Minardi","@id":"https:\/\/www.garvanacoustic.com\/fr\/#\/schema\/person\/6a1c1645f07f7a0aa5e018c2f909f355"},"headline":"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi &#8211; C.A.T.","datePublished":"2020-03-20T13:10:15+00:00","dateModified":"2021-03-09T13:17:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/"},"wordCount":179,"commentCount":0,"publisher":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/#primaryimage"},"thumbnailUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/maxresdefault-5.jpg","articleSection":["News &amp; Lifestyle"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/","url":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/","name":"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi - C.A.T. - Garvan Acoustic","isPartOf":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/#primaryimage"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/#primaryimage"},"thumbnailUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/maxresdefault-5.jpg","datePublished":"2020-03-20T13:10:15+00:00","dateModified":"2021-03-09T13:17:27+00:00","description":"Dans cette vid\u00e9o, enregistr\u00e9e avant l'urgence COVID-19, Davide Bertozzi de C.A.T. nous raconte une histoire de d'un syst\u00e8me audio multiroom fabriqu\u00e9 avec des enceintes acoustiques encastrables Garvan.Les zones sont g\u00e9r\u00e9es de mani\u00e8re ind\u00e9pendante et via une application de contr\u00f4le. Les haut-parleurs sont int\u00e9gr\u00e9s dans la maison et sont utilis\u00e9s pour \u00e9couter de la musique et des films.","breadcrumb":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/#primaryimage","url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/maxresdefault-5.jpg","contentUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2020\/09\/maxresdefault-5.jpg","width":1280,"height":720,"caption":"Audio Multiroom con diffusori da incasso,"},{"@type":"BreadcrumbList","@id":"https:\/\/www.garvanacoustic.com\/fr\/news-lifestyle\/audio-multiroom-avec-haut-parleurs-encastrables-mur-et-subwoofer-raconte-par-davide-bertozzi-c-a-t\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.garvanacoustic.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Audio multiroom avec haut-parleurs encastrables, mur et subwoofer racont\u00e9 par Davide Bertozzi &#8211; C.A.T."}]},{"@type":"WebSite","@id":"https:\/\/www.garvanacoustic.com\/fr\/#website","url":"https:\/\/www.garvanacoustic.com\/fr\/","name":"Garvan Acoustic","description":"Diffusori e trattamento acustico: scopri la qualit\u00e0 del Made in Italy","publisher":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.garvanacoustic.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.garvanacoustic.com\/fr\/#organization","name":"Garvan Acoustic","url":"https:\/\/www.garvanacoustic.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.garvanacoustic.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2018\/07\/garvan-acoustic-logo.png","contentUrl":"https:\/\/www.garvanacoustic.com\/wp-content\/uploads\/2018\/07\/garvan-acoustic-logo.png","width":400,"height":161,"caption":"Garvan Acoustic"},"image":{"@id":"https:\/\/www.garvanacoustic.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/garvanacoustic","https:\/\/www.instagram.com\/garvanacoustic\/"],"description":"Produttori di Diffusori Acustici e Pannelli Fonoassorbenti Made in Italy","email":"garvan@garvanacoustic.com","telephone":"0546 682097"},{"@type":"Person","@id":"https:\/\/www.garvanacoustic.com\/fr\/#\/schema\/person\/6a1c1645f07f7a0aa5e018c2f909f355","name":"Tommaso Minardi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c401eaabbdcdfbe0fe41e1798828bd51d99183ae86864950e8146a9c5cf079d?s=96&d=mm&r=g","caption":"Tommaso Minardi"},"url":"https:\/\/www.garvanacoustic.com\/fr\/author\/studioin3\/"}]}},"_links":{"self":[{"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/posts\/46332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/comments?post=46332"}],"version-history":[{"count":2,"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/posts\/46332\/revisions"}],"predecessor-version":[{"id":46338,"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/posts\/46332\/revisions\/46338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/media\/38973"}],"wp:attachment":[{"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/media?parent=46332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/categories?post=46332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.garvanacoustic.com\/fr\/wp-json\/wp\/v2\/tags?post=46332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}